{"id":456,"count":10,"description":"","link":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/","name":"El nostre equip opina","slug":"nuestro-equipo-opina-ca-ca","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El nostre equip opina Archives - Active Development<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nostre equip opina Archives - Active Development\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Active Development\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ActiveDe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.activede.com\/ca\/#organization\",\"name\":\"ACTIVE DEVELOPMENT\",\"url\":\"https:\/\/www.activede.com\/ca\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Active.Development\",\"https:\/\/www.linkedin.com\/company\/999561?trk=tyah&amp;amp;trkInfo=tarId:1419004716750,tas:active development,idx:2-1-3\",\"http:\/\/www.youtube.com\/user\/ActiveDevelopment\",\"https:\/\/twitter.com\/ActiveDe\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.activede.com\/ca\/#logo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/www.activede.com\/wp-content\/uploads\/2018\/10\/logoAD-min.png\",\"contentUrl\":\"https:\/\/www.activede.com\/wp-content\/uploads\/2018\/10\/logoAD-min.png\",\"width\":225,\"height\":51,\"caption\":\"ACTIVE DEVELOPMENT\"},\"image\":{\"@id\":\"https:\/\/www.activede.com\/ca\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.activede.com\/ca\/#website\",\"url\":\"https:\/\/www.activede.com\/ca\/\",\"name\":\"Active Development\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.activede.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.activede.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#webpage\",\"url\":\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/\",\"name\":\"El nostre equip opina Archives - Active Development\",\"isPartOf\":{\"@id\":\"https:\/\/www.activede.com\/ca\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.activede.com\/ca\/home_2026\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nostre equip opina\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nostre equip opina Archives - Active Development","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/","og_locale":"ca_ES","og_type":"article","og_title":"El nostre equip opina Archives - Active Development","og_url":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/","og_site_name":"Active Development","twitter_card":"summary_large_image","twitter_site":"@ActiveDe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.activede.com\/ca\/#organization","name":"ACTIVE DEVELOPMENT","url":"https:\/\/www.activede.com\/ca\/","sameAs":["https:\/\/www.facebook.com\/Active.Development","https:\/\/www.linkedin.com\/company\/999561?trk=tyah&amp;amp;trkInfo=tarId:1419004716750,tas:active development,idx:2-1-3","http:\/\/www.youtube.com\/user\/ActiveDevelopment","https:\/\/twitter.com\/ActiveDe"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.activede.com\/ca\/#logo","inLanguage":"ca","url":"https:\/\/www.activede.com\/wp-content\/uploads\/2018\/10\/logoAD-min.png","contentUrl":"https:\/\/www.activede.com\/wp-content\/uploads\/2018\/10\/logoAD-min.png","width":225,"height":51,"caption":"ACTIVE DEVELOPMENT"},"image":{"@id":"https:\/\/www.activede.com\/ca\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.activede.com\/ca\/#website","url":"https:\/\/www.activede.com\/ca\/","name":"Active Development","description":"","publisher":{"@id":"https:\/\/www.activede.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.activede.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"CollectionPage","@id":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#webpage","url":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/","name":"El nostre equip opina Archives - Active Development","isPartOf":{"@id":"https:\/\/www.activede.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.activede.com\/ca\/category\/nuestro-equipo-opina-ca-ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.activede.com\/ca\/home_2026\/"},{"@type":"ListItem","position":2,"name":"El nostre equip opina"}]}]}},"_links":{"self":[{"href":"https:\/\/www.activede.com\/ca\/wp-json\/wp\/v2\/categories\/456"}],"collection":[{"href":"https:\/\/www.activede.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.activede.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.activede.com\/ca\/wp-json\/wp\/v2\/posts?categories=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}